{"id":18234,"date":"2026-05-13T22:05:20","date_gmt":"2026-05-13T20:05:20","guid":{"rendered":"https:\/\/stephaneschweitzer.be\/propriete\/aline\/"},"modified":"2026-05-13T22:05:20","modified_gmt":"2026-05-13T20:05:20","slug":"aline","status":"publish","type":"estate","link":"https:\/\/stephaneschweitzer.be\/fr\/propriete\/aline\/","title":{"rendered":"Aline"},"content":{"rendered":"<p style=\"font-weight: 400;\">Une maison de charme aux multiples possibilit\u00e9s<\/p>\n<p style=\"font-weight: 400;\">Quartier Saint-Jacques, \u00e0 quelques pas de la Grand Place et de sa Coll\u00e9giale, <span> <\/span>d\u00e9couvrez cette maison au charme certain d\u2019une superficie de 250m2 \u00e0 proximit\u00e9 de toutes les commodit\u00e9s. <br \/>On y acc\u00e8de par une petite cour situ\u00e9 sur l\u2019avant de la maison.<\/p>\n<p style=\"font-weight: 400;\">Au rez-de-chauss\u00e9e en entrant, un espace utilis\u00e9 jusqu\u2019il y a peu comme Cabinet m\u00e9dical (et ce depuis de nombreuses ann\u00e9es) avec son bureau, sa salle d\u2019attente, une toilette ind\u00e9pendante et offrant de multiples autres possibilit\u00e9s d&rsquo;am\u00e9nagement.<br \/>Du hall privatif, sur la droite la salle \u00e0 manger avec feu ouvert qui donne sur la terrasse et le <span> <\/span>charmant jardin sans vis-\u00e0-vis orient\u00e9 au Sud-Ouest. Sur la droite la cuisine \u00e9quip\u00e9e.<br \/>A l\u2019\u00e9tage, sur la droite cot\u00e9 jardin un grand salon avec cassette ainsi qu\u2019un espace bureau, salle de jeu ou biblioth\u00e8que. Sur la gauche l\u2019acc\u00e8s vers la premi\u00e8re chambre (cot\u00e9 jardin), la salle de bain et douche, le dressing. Une toilette ind\u00e9pendante et la buanderie.<br \/>Au second, sur la gauche une grande chambre, une salle de bain et douche avec toilette.Sur la droite deux chambres en enfilade avec chacune sa mezzanine offrant un espace \u00ab optimis\u00e9 \u00bb.<\/p>\n<p>Cette maison aux multiples possibilit\u00e9s de vie ravira les amateurs de charme et d\u2019espace en ville.<\/p>\n<p style=\"font-weight: 400;\"><em>Prise de contact et rendez-vous par email aupr\u00e8s : stephane@stephaneschweitzer.be<\/em><span><em> <br \/><\/em><\/span><em>Informations donn\u00e9es \u00e0 titre informatif et non contractuelles.<\/em><\/p>\n","protected":false},"featured_media":0,"template":"","pays":[13],"class_list":["post-18234","estate","type-estate","status-publish","hentry","pays-belgique"],"acf":[],"_links":{"self":[{"href":"https:\/\/stephaneschweitzer.be\/fr\/wp-json\/wp\/v2\/estate\/18234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stephaneschweitzer.be\/fr\/wp-json\/wp\/v2\/estate"}],"about":[{"href":"https:\/\/stephaneschweitzer.be\/fr\/wp-json\/wp\/v2\/types\/estate"}],"wp:attachment":[{"href":"https:\/\/stephaneschweitzer.be\/fr\/wp-json\/wp\/v2\/media?parent=18234"}],"wp:term":[{"taxonomy":"pays","embeddable":true,"href":"https:\/\/stephaneschweitzer.be\/fr\/wp-json\/wp\/v2\/pays?post=18234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}